{"id":17784,"date":"2017-03-13T11:53:09","date_gmt":"2017-03-13T10:53:09","guid":{"rendered":"https:\/\/www.noatum.com\/concurso-mundial-paellas-sector-logistico\/"},"modified":"2017-03-13T11:53:09","modified_gmt":"2017-03-13T10:53:09","slug":"concurso-mundial-paellas-sector-logistico","status":"publish","type":"post","link":"https:\/\/www.noatum.com\/fr\/concurso-mundial-paellas-sector-logistico\/","title":{"rendered":"La 28e \u00e9dition du concours mondial de paellas du secteur logistique r\u00e9unit plus de 6 000 professionnels"},"content":{"rendered":"<h4>Plus de 200 repr\u00e9sentants de Noatum ont assist\u00e9 \u00e0 cet \u00e9v\u00e9nement, qui a eu lieu le 10 mars \u00e0 Valencia<\/h4>\n<p>&nbsp;<\/p>\n<p>Des employ\u00e9s et des clients de Noatum, soit au total plus de 200 repr\u00e9sentants, ont particip\u00e9 \u00e0 la 28e \u00e9dition du concours mondial de paellas adress\u00e9 aux entreprises du secteur logistique et organis\u00e9 chaque ann\u00e9e sur l\u2019esplanade de l\u2019ancienne gare El Grao \u00e0 Valencia. Cette \u00e9dition du concours a battu tous les records, avec 400 paellas inscrites et plus de 6 000 professionnels provenant de 250 entreprises du secteur.<\/p>\n<p>Le groupe Noatum a r\u00e9alis\u00e9 16 paellas, dont l\u2019une, pr\u00e9par\u00e9e par Combal\u00eda, a \u00e9t\u00e9 r\u00e9compens\u00e9e par le jury.<\/p>\n<p>Cet \u00e9v\u00e9nement, organis\u00e9 par la falla Dr J.J. D\u00f3mine-Port et Diario del Puerto, avec la collaboration de Noatum et d\u2019autres sponsors, s\u2019est confirm\u00e9 comme lieu de rencontre exceptionnel pour les entreprises du secteur logistique.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Plus de 200 repr\u00e9sentants de Noatum ont assist\u00e9 \u00e0 cet \u00e9v\u00e9nement, qui a eu lieu le 10 mars \u00e0 Valencia &nbsp; Des employ\u00e9s et des clients de Noatum, soit au<\/p>\n","protected":false},"author":1,"featured_media":17785,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31],"tags":[772,690],"class_list":["post-17784","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite","tag-espana-fr","tag-servicios-logisticos-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Noatum au concours mondial de paellas du secteur logistique<\/title>\n<meta name=\"description\" content=\"Plus de 200 repr\u00e9sentants de Noatum ont assist\u00e9 \u00e0 cet \u00e9v\u00e9nement, qui a eu lieu le 10 mars \u00e0 Valencia&quot;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.noatum.com\/fr\/concurso-mundial-paellas-sector-logistico\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Noatum au concours mondial de paellas du secteur logistique\" \/>\n<meta property=\"og:description\" content=\"Plus de 200 repr\u00e9sentants de Noatum ont assist\u00e9 \u00e0 cet \u00e9v\u00e9nement, qui a eu lieu le 10 mars \u00e0 Valencia&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noatum.com\/fr\/concurso-mundial-paellas-sector-logistico\/\" \/>\n<meta property=\"og:site_name\" content=\"Noatum\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-13T10:53:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.noatum.com\/wp-content\/uploads\/2017\/03\/Noatum_web1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"662\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"marmedsa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"marmedsa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.noatum.com\\\/fr\\\/concurso-mundial-paellas-sector-logistico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.noatum.com\\\/fr\\\/concurso-mundial-paellas-sector-logistico\\\/\"},\"author\":{\"name\":\"marmedsa\",\"@id\":\"https:\\\/\\\/www.noatum.com\\\/#\\\/schema\\\/person\\\/609872be83ffe2b5c3e0ac32078b56b3\"},\"headline\":\"La 28e \u00e9dition du concours mondial de paellas du secteur logistique r\u00e9unit plus de 6 000 professionnels\",\"datePublished\":\"2017-03-13T10:53:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.noatum.com\\\/fr\\\/concurso-mundial-paellas-sector-logistico\\\/\"},\"wordCount\":165,\"image\":{\"@id\":\"https:\\\/\\\/www.noatum.com\\\/fr\\\/concurso-mundial-paellas-sector-logistico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.noatum.com\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/Noatum_web1.jpg\",\"keywords\":[\"Espagne\",\"servicios log\u00edsticos\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.noatum.com\\\/fr\\\/concurso-mundial-paellas-sector-logistico\\\/\",\"url\":\"https:\\\/\\\/www.noatum.com\\\/fr\\\/concurso-mundial-paellas-sector-logistico\\\/\",\"name\":\"Noatum au concours mondial de paellas du secteur logistique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.noatum.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.noatum.com\\\/fr\\\/concurso-mundial-paellas-sector-logistico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.noatum.com\\\/fr\\\/concurso-mundial-paellas-sector-logistico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.noatum.com\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/Noatum_web1.jpg\",\"datePublished\":\"2017-03-13T10:53:09+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.noatum.com\\\/#\\\/schema\\\/person\\\/609872be83ffe2b5c3e0ac32078b56b3\"},\"description\":\"Plus de 200 repr\u00e9sentants de Noatum ont assist\u00e9 \u00e0 cet \u00e9v\u00e9nement, qui a eu lieu le 10 mars \u00e0 Valencia\\\"\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.noatum.com\\\/fr\\\/concurso-mundial-paellas-sector-logistico\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.noatum.com\\\/fr\\\/concurso-mundial-paellas-sector-logistico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.noatum.com\\\/fr\\\/concurso-mundial-paellas-sector-logistico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.noatum.com\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/Noatum_web1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.noatum.com\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/Noatum_web1.jpg\",\"width\":1400,\"height\":662,\"caption\":\"Concurso Mundial Paellas sector log\u00edstico\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.noatum.com\\\/fr\\\/concurso-mundial-paellas-sector-logistico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.noatum.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La 28e \u00e9dition du concours mondial de paellas du secteur logistique r\u00e9unit plus de 6 000 professionnels\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.noatum.com\\\/#website\",\"url\":\"https:\\\/\\\/www.noatum.com\\\/\",\"name\":\"Noatum\",\"description\":\"Excelencia en Servicios Mar\u00edtimos, Log\u00edsticos y Portuarios\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.noatum.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.noatum.com\\\/#\\\/schema\\\/person\\\/609872be83ffe2b5c3e0ac32078b56b3\",\"name\":\"marmedsa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/181e8a56335daafaee0929105ec92c8194d0adc2cdf37ca477466f1148d8331a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/181e8a56335daafaee0929105ec92c8194d0adc2cdf37ca477466f1148d8331a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/181e8a56335daafaee0929105ec92c8194d0adc2cdf37ca477466f1148d8331a?s=96&d=mm&r=g\",\"caption\":\"marmedsa\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Noatum au concours mondial de paellas du secteur logistique","description":"Plus de 200 repr\u00e9sentants de Noatum ont assist\u00e9 \u00e0 cet \u00e9v\u00e9nement, qui a eu lieu le 10 mars \u00e0 Valencia\"","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.noatum.com\/fr\/concurso-mundial-paellas-sector-logistico\/","og_locale":"fr_FR","og_type":"article","og_title":"Noatum au concours mondial de paellas du secteur logistique","og_description":"Plus de 200 repr\u00e9sentants de Noatum ont assist\u00e9 \u00e0 cet \u00e9v\u00e9nement, qui a eu lieu le 10 mars \u00e0 Valencia\"","og_url":"https:\/\/www.noatum.com\/fr\/concurso-mundial-paellas-sector-logistico\/","og_site_name":"Noatum","article_published_time":"2017-03-13T10:53:09+00:00","og_image":[{"width":1400,"height":662,"url":"https:\/\/www.noatum.com\/wp-content\/uploads\/2017\/03\/Noatum_web1.jpg","type":"image\/jpeg"}],"author":"marmedsa","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"marmedsa","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.noatum.com\/fr\/concurso-mundial-paellas-sector-logistico\/#article","isPartOf":{"@id":"https:\/\/www.noatum.com\/fr\/concurso-mundial-paellas-sector-logistico\/"},"author":{"name":"marmedsa","@id":"https:\/\/www.noatum.com\/#\/schema\/person\/609872be83ffe2b5c3e0ac32078b56b3"},"headline":"La 28e \u00e9dition du concours mondial de paellas du secteur logistique r\u00e9unit plus de 6 000 professionnels","datePublished":"2017-03-13T10:53:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.noatum.com\/fr\/concurso-mundial-paellas-sector-logistico\/"},"wordCount":165,"image":{"@id":"https:\/\/www.noatum.com\/fr\/concurso-mundial-paellas-sector-logistico\/#primaryimage"},"thumbnailUrl":"https:\/\/www.noatum.com\/wp-content\/uploads\/2017\/03\/Noatum_web1.jpg","keywords":["Espagne","servicios log\u00edsticos"],"articleSection":["Noticias"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.noatum.com\/fr\/concurso-mundial-paellas-sector-logistico\/","url":"https:\/\/www.noatum.com\/fr\/concurso-mundial-paellas-sector-logistico\/","name":"Noatum au concours mondial de paellas du secteur logistique","isPartOf":{"@id":"https:\/\/www.noatum.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.noatum.com\/fr\/concurso-mundial-paellas-sector-logistico\/#primaryimage"},"image":{"@id":"https:\/\/www.noatum.com\/fr\/concurso-mundial-paellas-sector-logistico\/#primaryimage"},"thumbnailUrl":"https:\/\/www.noatum.com\/wp-content\/uploads\/2017\/03\/Noatum_web1.jpg","datePublished":"2017-03-13T10:53:09+00:00","author":{"@id":"https:\/\/www.noatum.com\/#\/schema\/person\/609872be83ffe2b5c3e0ac32078b56b3"},"description":"Plus de 200 repr\u00e9sentants de Noatum ont assist\u00e9 \u00e0 cet \u00e9v\u00e9nement, qui a eu lieu le 10 mars \u00e0 Valencia\"","breadcrumb":{"@id":"https:\/\/www.noatum.com\/fr\/concurso-mundial-paellas-sector-logistico\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noatum.com\/fr\/concurso-mundial-paellas-sector-logistico\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.noatum.com\/fr\/concurso-mundial-paellas-sector-logistico\/#primaryimage","url":"https:\/\/www.noatum.com\/wp-content\/uploads\/2017\/03\/Noatum_web1.jpg","contentUrl":"https:\/\/www.noatum.com\/wp-content\/uploads\/2017\/03\/Noatum_web1.jpg","width":1400,"height":662,"caption":"Concurso Mundial Paellas sector log\u00edstico"},{"@type":"BreadcrumbList","@id":"https:\/\/www.noatum.com\/fr\/concurso-mundial-paellas-sector-logistico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.noatum.com\/fr\/"},{"@type":"ListItem","position":2,"name":"La 28e \u00e9dition du concours mondial de paellas du secteur logistique r\u00e9unit plus de 6 000 professionnels"}]},{"@type":"WebSite","@id":"https:\/\/www.noatum.com\/#website","url":"https:\/\/www.noatum.com\/","name":"Noatum","description":"Excelencia en Servicios Mar\u00edtimos, Log\u00edsticos y Portuarios","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noatum.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.noatum.com\/#\/schema\/person\/609872be83ffe2b5c3e0ac32078b56b3","name":"marmedsa","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/181e8a56335daafaee0929105ec92c8194d0adc2cdf37ca477466f1148d8331a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/181e8a56335daafaee0929105ec92c8194d0adc2cdf37ca477466f1148d8331a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/181e8a56335daafaee0929105ec92c8194d0adc2cdf37ca477466f1148d8331a?s=96&d=mm&r=g","caption":"marmedsa"}}]}},"_links":{"self":[{"href":"https:\/\/www.noatum.com\/fr\/wp-json\/wp\/v2\/posts\/17784","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noatum.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noatum.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noatum.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noatum.com\/fr\/wp-json\/wp\/v2\/comments?post=17784"}],"version-history":[{"count":0,"href":"https:\/\/www.noatum.com\/fr\/wp-json\/wp\/v2\/posts\/17784\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.noatum.com\/fr\/wp-json\/wp\/v2\/media\/17785"}],"wp:attachment":[{"href":"https:\/\/www.noatum.com\/fr\/wp-json\/wp\/v2\/media?parent=17784"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noatum.com\/fr\/wp-json\/wp\/v2\/categories?post=17784"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noatum.com\/fr\/wp-json\/wp\/v2\/tags?post=17784"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}